{"id":6743,"date":"2024-05-29T17:33:51","date_gmt":"2024-05-29T20:33:51","guid":{"rendered":"https:\/\/acsi-al.com.br\/site\/?p=6743"},"modified":"2024-05-29T17:33:51","modified_gmt":"2024-05-29T20:33:51","slug":"reuniao-com-a-aappe","status":"publish","type":"post","link":"https:\/\/acsi-al.com.br\/site\/reuniao-com-a-aappe\/","title":{"rendered":"Reuni\u00e3o com a AAPPE"},"content":{"rendered":"<p>Na manh\u00e3 desta quarta-feira 29 de maio de 2024, recebemos na Associa\u00e7\u00e3o Comercial de Santana do Ipanema as representantes da AAPPE: Wanessa e Kyslei . A reuni\u00e3o contou com a presen\u00e7a do presidente da ACSI Josinaldo Soares e a diretora e articuladora do projeto Empreender Jessyane Beatriz.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6744\" src=\"https:\/\/acsi-al.com.br\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-15.06.32-271x203.jpeg\" alt=\"\" width=\"271\" height=\"203\" srcset=\"https:\/\/acsi-al.com.br\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-15.06.32-271x203.jpeg 271w, https:\/\/acsi-al.com.br\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-15.06.32-768x576.jpeg 768w, https:\/\/acsi-al.com.br\/site\/wp-content\/uploads\/2024\/05\/WhatsApp-Image-2024-05-29-at-15.06.32.jpeg 1000w\" sizes=\"auto, (max-width: 271px) 100vw, 271px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quarta-feira 29 de maio de 2024, recebemos na Associa\u00e7\u00e3o Comercial de Santana do Ipanema as representantes da AAPPE: Wanessa e Kyslei . A reuni\u00e3o contou com a presen\u00e7a do presidente da ACSI Josinaldo Soares e a diretora e articuladora do projeto Empreender Jessyane Beatriz. &nbsp;<\/p>\n","protected":false},"author":10,"featured_media":6744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-6743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/posts\/6743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/comments?post=6743"}],"version-history":[{"count":1,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/posts\/6743\/revisions"}],"predecessor-version":[{"id":6745,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/posts\/6743\/revisions\/6745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/media\/6744"}],"wp:attachment":[{"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/media?parent=6743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/categories?post=6743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acsi-al.com.br\/site\/wp-json\/wp\/v2\/tags?post=6743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}